{"id":66,"count":3,"description":"","link":"https:\/\/optimacall.ro\/es\/etiqueta\/externalizacion-de-servicios-conformes\/","name":"externalizaci\u00f3n de servicios conformes","slug":"externalizacion-de-servicios-conformes","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.5 (Yoast SEO v26.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>externalizare servicii conforme Archives | Optima<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/optimacall.ro\/es\/etiqueta\/externalizacion-de-servicios-conformes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"externalizare servicii conforme Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/optimacall.ro\/es\/etiqueta\/externalizacion-de-servicios-conformes\/\" \/>\n<meta property=\"og:site_name\" content=\"Optima\" \/>\n<meta property=\"og:image\" content=\"https:\/\/optimacall.ro\/wp-content\/uploads\/2024\/01\/ai-human-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1487\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/optimacall.ro\/tag\/externalizare-servicii-conforme\/\",\"url\":\"https:\/\/optimacall.ro\/tag\/externalizare-servicii-conforme\/\",\"name\":\"externalizare servicii conforme Archives | Optima\",\"isPartOf\":{\"@id\":\"https:\/\/optimacall.ro\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/optimacall.ro\/tag\/externalizare-servicii-conforme\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/optimacall.ro\/tag\/externalizare-servicii-conforme\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Optima\",\"item\":\"https:\/\/optimacall.ro\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"externalizare servicii conforme\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/optimacall.ro\/#website\",\"url\":\"https:\/\/optimacall.ro\/\",\"name\":\"Optima\",\"description\":\"Solu\u021bii integrate de contact center \u0219i RPA\",\"publisher\":{\"@id\":\"https:\/\/optimacall.ro\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/optimacall.ro\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\/\/optimacall.ro\/#organization\",\"name\":\"Optima\",\"alternateName\":\"Optima Solutions Services\",\"url\":\"https:\/\/optimacall.ro\/\",\"logo\":{\"@id\":\"https:\/\/optimacall.ro\/tag\/externalizare-servicii-conforme\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\/\/optimacall.ro\/tag\/externalizare-servicii-conforme\/#local-main-organization-logo\"},\"sameAs\":[\"https:\/\/www.facebook.com\/optimacall4excellence\/\"],\"description\":\"Call center cu servicii de outsourcing\",\"legalName\":\"Optima Solutions Services SRL\",\"foundingDate\":\"2010-10-10\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"51\",\"maxValue\":\"200\"},\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/optimacall.ro\/tag\/externalizare-servicii-conforme\/#local-main-organization-logo\",\"url\":\"https:\/\/optimacall.ro\/wp-content\/uploads\/2024\/03\/cropped-cropped-logo-optima-rain.png\",\"contentUrl\":\"https:\/\/optimacall.ro\/wp-content\/uploads\/2024\/03\/cropped-cropped-logo-optima-rain.png\",\"width\":112,\"height\":112,\"caption\":\"Optima\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"externalizare servicii conforme Archives | Optima","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/optimacall.ro\/es\/etiqueta\/externalizacion-de-servicios-conformes\/","og_locale":"es_ES","og_type":"article","og_title":"externalizare servicii conforme Archives","og_url":"https:\/\/optimacall.ro\/es\/etiqueta\/externalizacion-de-servicios-conformes\/","og_site_name":"Optima","og_image":[{"width":2560,"height":1487,"url":"https:\/\/optimacall.ro\/wp-content\/uploads\/2024\/01\/ai-human-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/optimacall.ro\/tag\/externalizare-servicii-conforme\/","url":"https:\/\/optimacall.ro\/tag\/externalizare-servicii-conforme\/","name":"Externalizaci\u00f3n de servicios conformes Archivos | Optima","isPartOf":{"@id":"https:\/\/optimacall.ro\/#website"},"breadcrumb":{"@id":"https:\/\/optimacall.ro\/tag\/externalizare-servicii-conforme\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/optimacall.ro\/tag\/externalizare-servicii-conforme\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Optima","item":"https:\/\/optimacall.ro\/"},{"@type":"ListItem","position":2,"name":"externalizare servicii conforme"}]},{"@type":"WebSite","@id":"https:\/\/optimacall.ro\/#website","url":"https:\/\/optimacall.ro\/","name":"Optima","description":"Soluciones integradas de Contact Center y RPA","publisher":{"@id":"https:\/\/optimacall.ro\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/optimacall.ro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Organization","Place"],"@id":"https:\/\/optimacall.ro\/#organization","name":"Optima","alternateName":"Optima Solutions Services","url":"https:\/\/optimacall.ro\/","logo":{"@id":"https:\/\/optimacall.ro\/tag\/externalizare-servicii-conforme\/#local-main-organization-logo"},"image":{"@id":"https:\/\/optimacall.ro\/tag\/externalizare-servicii-conforme\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/optimacall4excellence\/"],"description":"Servicios de externalizaci\u00f3n de centros de llamadas","legalName":"Optima Solutions Services SRL","foundingDate":"2010-10-10","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"51","maxValue":"200"},"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/optimacall.ro\/tag\/externalizare-servicii-conforme\/#local-main-organization-logo","url":"https:\/\/optimacall.ro\/wp-content\/uploads\/2024\/03\/cropped-cropped-logo-optima-rain.png","contentUrl":"https:\/\/optimacall.ro\/wp-content\/uploads\/2024\/03\/cropped-cropped-logo-optima-rain.png","width":112,"height":112,"caption":"Optima"}]}},"_links":{"self":[{"href":"https:\/\/optimacall.ro\/es\/wp-json\/wp\/v2\/tags\/66","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/optimacall.ro\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/optimacall.ro\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/optimacall.ro\/es\/wp-json\/wp\/v2\/posts?tags=66"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}