{"id":8784,"date":"2024-08-02T09:27:45","date_gmt":"2024-08-02T07:27:45","guid":{"rendered":"https:\/\/optimacall.ro\/?p=8784"},"modified":"2024-08-02T10:14:59","modified_gmt":"2024-08-02T08:14:59","slug":"workshop-gdpr-optima","status":"publish","type":"post","link":"https:\/\/optimacall.ro\/it\/workshop-gdpr-optima\/","title":{"rendered":"Workshop GDPR presso Optima: protezione dei dati secondo gli standard futuri"},"content":{"rendered":"<style>.elementor-8784 .elementor-element.elementor-element-e2c6525{--display:flex;--flex-direction:column;--container-widget-width:100%;--container-widget-height:initial;--container-widget-flex-grow:0;--container-widget-align-self:initial;--flex-wrap-mobile:wrap;overflow:visible;}.elementor-8784 .elementor-element.elementor-element-e2c6525.e-con{--flex-grow:0;--flex-shrink:0;}.elementor-widget-image .widget-image-caption{color:var( --e-global-color-text );font-family:var( --e-global-typography-text-font-family ), Sans-serif;font-size:var( --e-global-typography-text-font-size );font-weight:var( --e-global-typography-text-font-weight );line-height:var( --e-global-typography-text-line-height );}.elementor-widget-heading .elementor-heading-title{font-family:var( --e-global-typography-primary-font-family ), Sans-serif;font-size:var( --e-global-typography-primary-font-size );font-weight:var( --e-global-typography-primary-font-weight );line-height:var( --e-global-typography-primary-line-height );color:var( --e-global-color-primary );}.elementor-8784 .elementor-element.elementor-element-deac12e{text-align:left;}.elementor-8784 .elementor-element.elementor-element-deac12e .elementor-heading-title{font-family:var( --e-global-typography-secondary-font-family ), Sans-serif;font-size:var( --e-global-typography-secondary-font-size );font-weight:var( --e-global-typography-secondary-font-weight );line-height:var( --e-global-typography-secondary-line-height );}.elementor-widget-text-editor{font-family:var( --e-global-typography-text-font-family ), Sans-serif;font-size:var( --e-global-typography-text-font-size );font-weight:var( --e-global-typography-text-font-weight );line-height:var( --e-global-typography-text-line-height );color:var( --e-global-color-text );}.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:var( --e-global-color-primary );}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap, .elementor-widget-text-editor.elementor-drop-cap-view-default .elementor-drop-cap{color:var( --e-global-color-primary );border-color:var( --e-global-color-primary );}.elementor-8784 .elementor-element.elementor-element-a98ecd9{width:auto;max-width:auto;margin:0px 0px calc(var(--kit-widget-spacing, 0px) + 0px) 0px;padding:19px 19px 19px 19px;text-align:justify;}.elementor-8784 .elementor-element.elementor-element-a98ecd9.elementor-element{--align-self:stretch;}.elementor-widget-button .elementor-button{background-color:var( --e-global-color-accent );font-family:var( --e-global-typography-accent-font-family ), Sans-serif;font-size:var( --e-global-typography-accent-font-size );font-weight:var( --e-global-typography-accent-font-weight );line-height:var( --e-global-typography-accent-line-height );}.elementor-8784 .elementor-element.elementor-element-0a8d661{padding:-1px -1px -1px -1px;}.elementor-8784 .elementor-element.elementor-element-0a8d661 .elementor-button-content-wrapper{flex-direction:row;}.elementor-8784 .elementor-element.elementor-element-0a8d661 .elementor-button{box-shadow:21px 7px 25px -2px rgba(0,0,0,0.5);border-radius:-2px -2px -2px -2px;}:root{--page-title-display:none;}@media(max-width:1024px){.elementor-widget-image .widget-image-caption{font-size:var( --e-global-typography-text-font-size );line-height:var( --e-global-typography-text-line-height );}.elementor-widget-heading .elementor-heading-title{font-size:var( --e-global-typography-primary-font-size );line-height:var( --e-global-typography-primary-line-height );}.elementor-8784 .elementor-element.elementor-element-deac12e .elementor-heading-title{font-size:var( --e-global-typography-secondary-font-size );line-height:var( --e-global-typography-secondary-line-height );}.elementor-widget-text-editor{font-size:var( --e-global-typography-text-font-size );line-height:var( --e-global-typography-text-line-height );}.elementor-widget-button .elementor-button{font-size:var( --e-global-typography-accent-font-size );line-height:var( --e-global-typography-accent-line-height );}}@media(max-width:767px){.elementor-widget-image .widget-image-caption{font-size:var( --e-global-typography-text-font-size );line-height:var( --e-global-typography-text-line-height );}.elementor-widget-heading .elementor-heading-title{font-size:var( --e-global-typography-primary-font-size );line-height:var( --e-global-typography-primary-line-height );}.elementor-8784 .elementor-element.elementor-element-deac12e .elementor-heading-title{font-size:var( --e-global-typography-secondary-font-size );line-height:var( --e-global-typography-secondary-line-height );}.elementor-widget-text-editor{font-size:var( --e-global-typography-text-font-size );line-height:var( --e-global-typography-text-line-height );}.elementor-widget-button .elementor-button{font-size:var( --e-global-typography-accent-font-size );line-height:var( --e-global-typography-accent-line-height );}}<\/style>\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"8784\" class=\"elementor elementor-8784\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e2c6525 e-flex e-con-boxed e-con e-parent\" data-id=\"e2c6525\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-487ddb1 elementor-widget elementor-widget-image\" data-id=\"487ddb1\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1280\" height=\"640\" src=\"https:\/\/optimacall.ro\/wp-content\/uploads\/2024\/08\/Banner-Articole-Blog.png\" class=\"attachment-full size-full wp-image-8786\" alt=\"Workshop GDPR presso Optima\" srcset=\"https:\/\/optimacall.ro\/wp-content\/uploads\/2024\/08\/Banner-Articole-Blog.png 1280w, https:\/\/optimacall.ro\/wp-content\/uploads\/2024\/08\/Banner-Articole-Blog-300x150.png 300w, https:\/\/optimacall.ro\/wp-content\/uploads\/2024\/08\/Banner-Articole-Blog-1024x512.png 1024w, https:\/\/optimacall.ro\/wp-content\/uploads\/2024\/08\/Banner-Articole-Blog-768x384.png 768w, https:\/\/optimacall.ro\/wp-content\/uploads\/2024\/08\/Banner-Articole-Blog-18x9.png 18w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-deac12e elementor-widget elementor-widget-heading\" data-id=\"deac12e\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Workshop GDPR presso Optima: protezione dei dati secondo gli standard futuri<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a98ecd9 elementor-widget__width-auto elementor-widget elementor-widget-text-editor\" data-id=\"a98ecd9\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Optima riconosce l'importanza della protezione dei dati personali e si impegna a rispettare gli standard pi\u00f9 elevati in questo settore. Per mantenere e migliorare costantemente il nostro livello di conformit\u00e0 al Regolamento generale sulla protezione dei dati (GDPR), organizziamo sessioni di aggiornamento trimestrali per tutti i nostri dipendenti. Questi workshop sono essenziali per garantire che ogni membro del team sia aggiornato sulle ultime normative e pratiche in materia di protezione dei dati.<\/p><p><strong>Importanza della conformit\u00e0 al GDPR<\/strong><\/p><p>La conformit\u00e0 al GDPR non \u00e8 solo un requisito legale, ma anche una dimostrazione dell'impegno di un'azienda a proteggere i diritti e la privacy degli interessati. In Optima siamo consapevoli che la conformit\u00e0 a queste norme non solo ci protegge dalle sanzioni, ma migliora anche la nostra reputazione e le relazioni con i clienti. Le nostre sessioni di formazione sono pensate per garantire che tutti i nostri dipendenti siano consapevoli e in grado di applicare correttamente i principi del GDPR.<\/p><p><strong>Struttura delle sessioni di formazione sul GDPR<\/strong><\/p><p>Le sessioni di formazione sono strutturate in modo da coprire in dettaglio vari aspetti chiave del GDPR. Dai principi fondamentali del regolamento, come la liceit\u00e0, la correttezza e la trasparenza nel trattamento dei dati, ai diritti degli interessati e alle responsabilit\u00e0 dei responsabili del trattamento, ogni argomento viene affrontato in modo completo e pratico.<\/p><p><strong>Argomenti principali dei workshop<\/strong><\/p><h3>Principi fondamentali del GDPR<\/h3><p>Nel corso di queste sessioni vengono affrontati diversi argomenti essenziali per la comprensione e la corretta applicazione dei principi del GDPR. Il programma \u00e8 strutturato in modo da fornire una revisione dettagliata del regolamento, assicurando che tutti i partecipanti comprendano appieno i loro obblighi e le loro responsabilit\u00e0. La sessione offre anche l'opportunit\u00e0 di discutere le sfide pratiche incontrate nel lavoro quotidiano di implementazione del GDPR e le soluzioni efficaci per superarle.<\/p><h3>Identificazione corretta del cliente e prevenzione della divulgazione non autorizzata<\/h3><p>Una parte importante delle nostre sessioni di formazione si concentra sulle procedure per identificare correttamente i clienti e prevenire la divulgazione non autorizzata di informazioni personali. I dipendenti vengono istruiti a seguire regole rigorose per l'accesso e l'utilizzo dei dati, a monitorare e segnalare qualsiasi attivit\u00e0 sospetta e ad adottare misure preventive per evitare violazioni della sicurezza.<\/p><h3>Diritti degli interessati<\/h3><p>Un altro aspetto cruciale dei workshop \u00e8 la formazione dei dipendenti sui diritti degli interessati. Questi includono il diritto di accesso ai dati, il diritto alla rettifica, il diritto alla cancellazione (il diritto all'oblio), il diritto alla limitazione del trattamento, il diritto alla portabilit\u00e0 dei dati e il diritto di opposizione. La comprensione e il rispetto di questi diritti sono essenziali per mantenere la conformit\u00e0 al GDPR.<\/p><h3>Valutazione finale e assistenza individuale<\/h3><p>Al termine di ogni sessione di formazione, i partecipanti eseguono una valutazione per verificare le loro conoscenze. Questo ci aiuta a individuare eventuali lacune e a fornire un'assistenza personalizzata laddove necessario, assicurando che ogni dipendente sia pienamente preparato a gestire correttamente le informazioni personali dei clienti.<\/p><p><strong>Vantaggi della partecipazione ai workshop sul GDPR<\/strong><\/p><p>Partecipando a queste sessioni trimestrali di riqualificazione, i nostri dipendenti non solo migliorano le loro conoscenze e competenze, ma contribuiscono anche a rafforzare la posizione di Optima come partner di fiducia per la protezione dei dati. In un ambiente dinamico e in continua evoluzione, garantire la conformit\u00e0 al GDPR \u00e8 essenziale per proteggere la privacy e la sicurezza dei dati dei nostri clienti.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0a8d661 elementor-widget elementor-widget-button\" data-id=\"0a8d661\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/optimacall.ro\/en\/career\/%20\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-hand-point-right\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M428.8 137.6h-86.177a115.52 115.52 0 0 0 2.176-22.4c0-47.914-35.072-83.2-92-83.2-45.314 0-57.002 48.537-75.707 78.784-7.735 12.413-16.994 23.317-25.851 33.253l-.131.146-.129.148C135.662 161.807 127.764 168 120.8 168h-2.679c-5.747-4.952-13.536-8-22.12-8H32c-17.673 0-32 12.894-32 28.8v230.4C0 435.106 14.327 448 32 448h64c8.584 0 16.373-3.048 22.12-8h2.679c28.688 0 67.137 40 127.2 40h21.299c62.542 0 98.8-38.658 99.94-91.145 12.482-17.813 18.491-40.785 15.985-62.791A93.148 93.148 0 0 0 393.152 304H428.8c45.435 0 83.2-37.584 83.2-83.2 0-45.099-38.101-83.2-83.2-83.2zm0 118.4h-91.026c12.837 14.669 14.415 42.825-4.95 61.05 11.227 19.646 1.687 45.624-12.925 53.625 6.524 39.128-10.076 61.325-50.6 61.325H248c-45.491 0-77.21-35.913-120-39.676V215.571c25.239-2.964 42.966-21.222 59.075-39.596 11.275-12.65 21.725-25.3 30.799-39.875C232.355 112.712 244.006 80 252.8 80c23.375 0 44 8.8 44 35.2 0 35.2-26.4 53.075-26.4 70.4h158.4c18.425 0 35.2 16.5 35.2 35.2 0 18.975-16.225 35.2-35.2 35.2zM88 384c0 13.255-10.745 24-24 24s-24-10.745-24-24 10.745-24 24-24 24 10.745 24 24z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Conosciamoci!<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Workshop-ul GDPR la Optima: Protec\u021bia Datelor la Standardele Viitorului Optima recunoa\u0219te importan\u021ba protec\u021biei datelor cu caracter personal \u0219i se angajeaz\u0103 s\u0103 respecte cele mai \u00eenalte standarde \u00een acest domeniu. Pentru a men\u021bine \u0219i \u00eembun\u0103t\u0103\u021bi constant nivelul de conformitate cu Regulamentul General privind Protec\u021bia Datelor (GDPR), organiz\u0103m sesiuni trimestriale de retraining pentru to\u021bi angaja\u021bii no\u0219tri. Aceste [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8786,"comment_status":"open","ping_status":"closed","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8784","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized-ro"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.5 (Yoast SEO v26.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Workshop-ul GDPR la Optima<\/title>\n<meta name=\"description\" content=\"Workshop-ul GDPR la Optima asigur\u0103 standarde ridicate de protec\u021bia datelor cu sesiuni trimestriale de retraining.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/optimacall.ro\/it\/workshop-gdpr-optima\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Workshop-ul GDPR la Optima: Protec\u021bia Datelor la Standardele Viitorului\u200b\" \/>\n<meta property=\"og:description\" content=\"Workshop-ul GDPR la Optima asigur\u0103 standarde ridicate de protec\u021bia datelor cu sesiuni trimestriale de retraining.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/optimacall.ro\/it\/workshop-gdpr-optima\/\" \/>\n<meta property=\"og:site_name\" content=\"Optima\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/optimacall4excellence\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-02T07:27:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-02T08:14:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/optimacall.ro\/wp-content\/uploads\/2024\/08\/Banner-Articole-Blog.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Lungu Georgiana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lungu Georgiana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/optimacall.ro\/workshop-gdpr-optima\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/optimacall.ro\/workshop-gdpr-optima\/\"},\"author\":{\"name\":\"Lungu Georgiana\",\"@id\":\"https:\/\/optimacall.ro\/#\/schema\/person\/bfc6d7b85ac797851f1c25ccc9162f17\"},\"headline\":\"Workshop-ul GDPR la Optima: Protec\u021bia Datelor la Standardele Viitorului\u200b\",\"datePublished\":\"2024-08-02T07:27:45+00:00\",\"dateModified\":\"2024-08-02T08:14:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/optimacall.ro\/workshop-gdpr-optima\/\"},\"wordCount\":636,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\/\/optimacall.ro\/#organization\"},\"image\":{\"@id\":\"https:\/\/optimacall.ro\/workshop-gdpr-optima\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/optimacall.ro\/wp-content\/uploads\/2024\/08\/Banner-Articole-Blog.png\",\"articleSection\":[\"Uncategorized @ro\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/optimacall.ro\/workshop-gdpr-optima\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/optimacall.ro\/workshop-gdpr-optima\/\",\"url\":\"https:\/\/optimacall.ro\/workshop-gdpr-optima\/\",\"name\":\"Workshop-ul GDPR la Optima\",\"isPartOf\":{\"@id\":\"https:\/\/optimacall.ro\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/optimacall.ro\/workshop-gdpr-optima\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/optimacall.ro\/workshop-gdpr-optima\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/optimacall.ro\/wp-content\/uploads\/2024\/08\/Banner-Articole-Blog.png\",\"datePublished\":\"2024-08-02T07:27:45+00:00\",\"dateModified\":\"2024-08-02T08:14:59+00:00\",\"description\":\"Workshop-ul GDPR la Optima asigur\u0103 standarde ridicate de protec\u021bia datelor cu sesiuni trimestriale de retraining.\",\"breadcrumb\":{\"@id\":\"https:\/\/optimacall.ro\/workshop-gdpr-optima\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/optimacall.ro\/workshop-gdpr-optima\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/optimacall.ro\/workshop-gdpr-optima\/#primaryimage\",\"url\":\"https:\/\/optimacall.ro\/wp-content\/uploads\/2024\/08\/Banner-Articole-Blog.png\",\"contentUrl\":\"https:\/\/optimacall.ro\/wp-content\/uploads\/2024\/08\/Banner-Articole-Blog.png\",\"width\":1280,\"height\":640,\"caption\":\"Workshop GDPR la Optima\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/optimacall.ro\/workshop-gdpr-optima\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Optima\",\"item\":\"https:\/\/optimacall.ro\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Workshop-ul GDPR la Optima: Protec\u021bia Datelor la Standardele Viitorului\u200b\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/optimacall.ro\/#website\",\"url\":\"https:\/\/optimacall.ro\/\",\"name\":\"Optima\",\"description\":\"Solu\u021bii integrate de contact center \u0219i RPA\",\"publisher\":{\"@id\":\"https:\/\/optimacall.ro\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/optimacall.ro\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\/\/optimacall.ro\/#organization\",\"name\":\"Optima\",\"alternateName\":\"Optima Solutions Services\",\"url\":\"https:\/\/optimacall.ro\/\",\"logo\":{\"@id\":\"https:\/\/optimacall.ro\/workshop-gdpr-optima\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\/\/optimacall.ro\/workshop-gdpr-optima\/#local-main-organization-logo\"},\"sameAs\":[\"https:\/\/www.facebook.com\/optimacall4excellence\/\"],\"description\":\"Call center cu servicii de outsourcing\",\"legalName\":\"Optima Solutions Services SRL\",\"foundingDate\":\"2010-10-10\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"51\",\"maxValue\":\"200\"},\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/optimacall.ro\/#\/schema\/person\/bfc6d7b85ac797851f1c25ccc9162f17\",\"name\":\"Lungu Georgiana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/optimacall.ro\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c78e6266f70e0faeddb4a45662054b6911b0554f1250eec43817bde805ba2bc5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c78e6266f70e0faeddb4a45662054b6911b0554f1250eec43817bde805ba2bc5?s=96&d=mm&r=g\",\"caption\":\"Lungu Georgiana\"},\"url\":\"https:\/\/optimacall.ro\/it\/author\/georgiana_lungu\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/optimacall.ro\/workshop-gdpr-optima\/#local-main-organization-logo\",\"url\":\"https:\/\/optimacall.ro\/wp-content\/uploads\/2024\/03\/cropped-cropped-logo-optima-rain.png\",\"contentUrl\":\"https:\/\/optimacall.ro\/wp-content\/uploads\/2024\/03\/cropped-cropped-logo-optima-rain.png\",\"width\":112,\"height\":112,\"caption\":\"Optima\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Workshop GDPR presso Optima","description":"Il workshop GDPR di Optima garantisce elevati standard di protezione dei dati con sessioni di aggiornamento trimestrali.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/optimacall.ro\/it\/workshop-gdpr-optima\/","og_locale":"it_IT","og_type":"article","og_title":"Workshop-ul GDPR la Optima: Protec\u021bia Datelor la Standardele Viitorului\u200b","og_description":"Workshop-ul GDPR la Optima asigur\u0103 standarde ridicate de protec\u021bia datelor cu sesiuni trimestriale de retraining.","og_url":"https:\/\/optimacall.ro\/it\/workshop-gdpr-optima\/","og_site_name":"Optima","article_publisher":"https:\/\/www.facebook.com\/optimacall4excellence\/","article_published_time":"2024-08-02T07:27:45+00:00","article_modified_time":"2024-08-02T08:14:59+00:00","og_image":[{"width":1280,"height":640,"url":"https:\/\/optimacall.ro\/wp-content\/uploads\/2024\/08\/Banner-Articole-Blog.png","type":"image\/png"}],"author":"Lungu Georgiana","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Lungu Georgiana","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/optimacall.ro\/workshop-gdpr-optima\/#article","isPartOf":{"@id":"https:\/\/optimacall.ro\/workshop-gdpr-optima\/"},"author":{"name":"Lungu Georgiana","@id":"https:\/\/optimacall.ro\/#\/schema\/person\/bfc6d7b85ac797851f1c25ccc9162f17"},"headline":"Workshop-ul GDPR la Optima: Protec\u021bia Datelor la Standardele Viitorului\u200b","datePublished":"2024-08-02T07:27:45+00:00","dateModified":"2024-08-02T08:14:59+00:00","mainEntityOfPage":{"@id":"https:\/\/optimacall.ro\/workshop-gdpr-optima\/"},"wordCount":636,"commentCount":2,"publisher":{"@id":"https:\/\/optimacall.ro\/#organization"},"image":{"@id":"https:\/\/optimacall.ro\/workshop-gdpr-optima\/#primaryimage"},"thumbnailUrl":"https:\/\/optimacall.ro\/wp-content\/uploads\/2024\/08\/Banner-Articole-Blog.png","articleSection":["Uncategorized @ro"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/optimacall.ro\/workshop-gdpr-optima\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/optimacall.ro\/workshop-gdpr-optima\/","url":"https:\/\/optimacall.ro\/workshop-gdpr-optima\/","name":"Workshop GDPR presso Optima","isPartOf":{"@id":"https:\/\/optimacall.ro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/optimacall.ro\/workshop-gdpr-optima\/#primaryimage"},"image":{"@id":"https:\/\/optimacall.ro\/workshop-gdpr-optima\/#primaryimage"},"thumbnailUrl":"https:\/\/optimacall.ro\/wp-content\/uploads\/2024\/08\/Banner-Articole-Blog.png","datePublished":"2024-08-02T07:27:45+00:00","dateModified":"2024-08-02T08:14:59+00:00","description":"Il workshop GDPR di Optima garantisce elevati standard di protezione dei dati con sessioni di aggiornamento trimestrali.","breadcrumb":{"@id":"https:\/\/optimacall.ro\/workshop-gdpr-optima\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/optimacall.ro\/workshop-gdpr-optima\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/optimacall.ro\/workshop-gdpr-optima\/#primaryimage","url":"https:\/\/optimacall.ro\/wp-content\/uploads\/2024\/08\/Banner-Articole-Blog.png","contentUrl":"https:\/\/optimacall.ro\/wp-content\/uploads\/2024\/08\/Banner-Articole-Blog.png","width":1280,"height":640,"caption":"Workshop GDPR la Optima"},{"@type":"BreadcrumbList","@id":"https:\/\/optimacall.ro\/workshop-gdpr-optima\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Optima","item":"https:\/\/optimacall.ro\/"},{"@type":"ListItem","position":2,"name":"Workshop-ul GDPR la Optima: Protec\u021bia Datelor la Standardele Viitorului\u200b"}]},{"@type":"WebSite","@id":"https:\/\/optimacall.ro\/#website","url":"https:\/\/optimacall.ro\/","name":"Optima","description":"Soluzioni integrate di contact center e RPA","publisher":{"@id":"https:\/\/optimacall.ro\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/optimacall.ro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/optimacall.ro\/#organization","name":"Optima","alternateName":"Optima Solutions Services","url":"https:\/\/optimacall.ro\/","logo":{"@id":"https:\/\/optimacall.ro\/workshop-gdpr-optima\/#local-main-organization-logo"},"image":{"@id":"https:\/\/optimacall.ro\/workshop-gdpr-optima\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/optimacall4excellence\/"],"description":"Servizi di call center in outsourcing","legalName":"Optima Solutions Services SRL","foundingDate":"2010-10-10","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"51","maxValue":"200"},"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/optimacall.ro\/#\/schema\/person\/bfc6d7b85ac797851f1c25ccc9162f17","name":"Lungu Georgiana","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/optimacall.ro\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c78e6266f70e0faeddb4a45662054b6911b0554f1250eec43817bde805ba2bc5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c78e6266f70e0faeddb4a45662054b6911b0554f1250eec43817bde805ba2bc5?s=96&d=mm&r=g","caption":"Lungu Georgiana"},"url":"https:\/\/optimacall.ro\/it\/author\/georgiana_lungu\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/optimacall.ro\/workshop-gdpr-optima\/#local-main-organization-logo","url":"https:\/\/optimacall.ro\/wp-content\/uploads\/2024\/03\/cropped-cropped-logo-optima-rain.png","contentUrl":"https:\/\/optimacall.ro\/wp-content\/uploads\/2024\/03\/cropped-cropped-logo-optima-rain.png","width":112,"height":112,"caption":"Optima"}]}},"_links":{"self":[{"href":"https:\/\/optimacall.ro\/it\/wp-json\/wp\/v2\/posts\/8784","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/optimacall.ro\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/optimacall.ro\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/optimacall.ro\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/optimacall.ro\/it\/wp-json\/wp\/v2\/comments?post=8784"}],"version-history":[{"count":1,"href":"https:\/\/optimacall.ro\/it\/wp-json\/wp\/v2\/posts\/8784\/revisions"}],"predecessor-version":[{"id":8795,"href":"https:\/\/optimacall.ro\/it\/wp-json\/wp\/v2\/posts\/8784\/revisions\/8795"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/optimacall.ro\/it\/wp-json\/wp\/v2\/media\/8786"}],"wp:attachment":[{"href":"https:\/\/optimacall.ro\/it\/wp-json\/wp\/v2\/media?parent=8784"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/optimacall.ro\/it\/wp-json\/wp\/v2\/categories?post=8784"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/optimacall.ro\/it\/wp-json\/wp\/v2\/tags?post=8784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}